{"id":2219,"date":"2026-03-27T20:25:00","date_gmt":"2026-03-27T20:25:00","guid":{"rendered":"https:\/\/houseofarchitects.nl\/?page_id=2219"},"modified":"2026-03-27T20:42:53","modified_gmt":"2026-03-27T20:42:53","slug":"visie","status":"publish","type":"page","link":"https:\/\/houseofarchitects.nl\/el\/visie\/","title":{"rendered":"Visie"},"content":{"rendered":"<div class=\"row cf\" style=\"background-size: auto;padding: 24px 0;\"><div class=\"wrap\"> \n<div class=\"shortcode_text_block\" style=\"width:60%;text-align: left;\"><h3 class=\"title\" style=\"color: #000;\">Visie<\/h3><p class=\"lead\" style=\"color:#333;\">\n<p>Wij ontwerpen vanuit de vraag hoe we willen wonen.<\/p>\n<p>Niet als object,<br \/>\nmaar als onderdeel van een groter geheel \u2014<br \/>\nin relatie tot plek, landschap en gebruik.<\/p>\n<p>Door te analyseren, te ordenen en weg te laten<br \/>\nbrengen we complexiteit terug tot de essentie.<\/p>\n<p>Zo ontstaat een helder concept<br \/>\nwaarin alles met elkaar samenhangt.<\/p>\n<p>In die eenvoud ontstaat rust en vanzelfsprekendheid.<\/p>\n<p>Onze ontwerpen zijn zorgvuldig uitgewerkt<br \/>\nen worden met dezelfde precisie gerealiseerd.<\/p>\n<p>Het resultaat is een tijdloze architectuur<br \/>\ndie zich voegt naar de plek<br \/>\nen deze versterkt.<\/p>\n<\/p><\/div>\n <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/pages\/2219"}],"collection":[{"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/comments?post=2219"}],"version-history":[{"count":5,"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/pages\/2219\/revisions"}],"predecessor-version":[{"id":2227,"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/pages\/2219\/revisions\/2227"}],"wp:attachment":[{"href":"https:\/\/houseofarchitects.nl\/el\/wp-json\/wp\/v2\/media?parent=2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}